{"id":368,"count":3,"description":"","link":"https:\/\/budapest-trend.eu\/uk\/tag\/dozvillya","name":"\u0434\u043e\u0437\u0432\u0456\u043b\u043b\u044f","slug":"dozvillya","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/tags\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/posts?tags=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}