{"id":669,"count":1,"description":"","link":"https:\/\/budapest-trend.eu\/uk\/tag\/francheska-torochyk","name":"\u0424\u0440\u0430\u043d\u0447\u0435\u0441\u043a\u0430 \u0422\u044c\u043e\u0440\u043e\u0447\u0438\u043a","slug":"francheska-torochyk","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/tags\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/budapest-trend.eu\/uk\/wp-json\/wp\/v2\/posts?tags=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}